{"id":1842,"date":"2024-11-03T00:00:00","date_gmt":"2024-11-02T23:00:00","guid":{"rendered":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/"},"modified":"2024-11-03T00:00:00","modified_gmt":"2024-11-02T23:00:00","slug":"fotovoltaico-offerta-impianto-80kw","status":"publish","type":"post","link":"https:\/\/seasolar.it\/fr\/fotovoltaico-offerta-impianto-80kw\/","title":{"rendered":"Fotovoltaico offerta impianto 80kW"},"content":{"rendered":"<p>Offerta impianto fotovoltaico \u201cchiavi in mano\u201d 80KW (terminata)<\/p>\n<p>L\u2019impianto fotovoltaico ha una potenza nominale di 80,08 KWp e comprende:<\/p>\n<ul>\n<li>182 Moduli fotovoltaici in silicio monocristallino Q-CELLS da 440W, garanzia sul prodotto 25 anni, garanzia sulla produzione 30 anni<\/li>\n<li>Inverter trifase SOLAX da 80kW, sistema di monitoraggio e WI-FI integrati, funzione autoconsumo, garanzia sul prodotto 5 anni estendibile fino a 20 anni<\/li>\n<li>Strutture di sostegno per installazione aderente e complanare su copertura a falda inclinata in lamiera grecata<\/li>\n<li>Quadro di campo<\/li>\n<li>Quadro generale fotovoltaico e di interfaccia conforme alla normativa CEI 0-21<\/li>\n<\/ul>\n<p>Il prezzo \u00ab\u00a0chiavi in mano\u00a0\u00bb include:<\/p>\n<ul>\n<li>Sopralluogo sul sito di installazione<\/li>\n<li>Relazione di fattibilit\u00e0 tecnica ed economica (business plan)<\/li>\n<li>Progetto esecutivo<\/li>\n<li>Istruzione ed inoltro richiesta di connessione di rete al Gestore competente<\/li>\n<li>Predisposizione Piano delle misure per la sicurezza fisica e l&rsquo;integrit\u00e0 dei lavoratori<\/li>\n<li>Istruzione ed inoltro richiesta di convenzione al Gestore dei Servizi Energetici<\/li>\n<li>Consegna documentazione tecnica per la denuncia di apertura officina elettrica<\/li>\n<\/ul>\n<p>Il prezzo include inoltre:<\/p>\n<ul>\n<li>Primo anno di manutenzione ordinaria dell&rsquo;impianto<\/li>\n<li>Primo anno di monitoraggio e gestione da remoto dell&rsquo;impianto<\/li>\n<\/ul>\n<p>Seasolar offre un servizio completo \u201cchiavi in mano\u201d al privato o l\u2019impresa che desidera realizzare un impianto fotovoltaico sul proprio edificio, a parziale o totale copertura del proprio fabbisogno energetico.<\/p>\n<p>Progettiamo e installiamo impianti fotovoltaici con l\u2019obiettivo di ridurre o azzerare il fabbisogno energetico dell\u2019immobile utilizzando prodotti di alta qualit\u00e0 scelti grazie all\u2019esperienza ultra decennale maturata nel settore.<\/p>\n<p>Proponiamo moduli fotovoltaici ad alta efficienza abbinati ai migliori inverter con oltre 20 anni di garanzia.<\/p>\n<p>Ciascuna offerta pu\u00f2 essere personalizzata attingendo al vasto e sempre aggiornato <a href=\"https:\/\/seasolargroup.com\/products\/\">catalogo prodotti<\/a> che comprende anche sistemi di accumulo, sistemi per la mobilit\u00e0 elettrica e accessori.<\/p>\n<p>Sfrutta al massimo lo spazio disponibile sul tuo tetto installando la massima potenza ottenibile con i nostri moduli fotovoltaici ad alta efficienza.<\/p>\n<p>Massimizza l&rsquo;autoconsumo dell\u2019energia prodotta dal tuo impianto con i nuovi inverter dotati di sistema di accumulo.<\/p>\n<p>Tieni sotto controllo la produzione e i consumi del tuo impianto comodamente dal tuo smartphone o dal tuo PC.<\/p>\n<p>Per informazioni chiama il nostro numero verde gratuito<br \/>\n<a href=\"tel:+39800513618\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-11741 size-medium alignnone\" src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2020\/04\/logo.png?resize=300%2C143&#038;ssl=1\" alt=\"numero verde\" width=\"300\" height=\"143\" data-id=\"11741\" \/><\/a><br \/>\n(Offerta limitata e valida fino ad esaurimento scorte)<br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Prodotti<\/h2>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"12227\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2020\/07\/bifacial-300x300.jpg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-12227\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/product\/q-cells-q-tron-s-g3r-12-bfg-450w\/\">Modulo fotovoltaico Q-CELLS Q.TRON S-G3R.12 BFG<\/a><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-id=\"10755\"  src=\"https:\/\/i0.wp.com\/seasolargroup.com\/wp-content\/uploads\/2020\/03\/2EU-INV-RIGHT-1024x819-1-300x219.jpg?resize=300%2C219&#038;ssl=1\" alt=\"\" width=\"300\" height=\"219\" class=\"alignnone size-medium wp-image-10755\" \/><br \/>\n<a href=\"https:\/\/seasolargroup.com\/it\/product\/solax-x3-fth-80k\/\">Inverter SOLAX X3 FTH 80K<\/a><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Links<\/h2>\n<p><a href=\"https:\/\/www.q-cells.com\/\" rel=\"noopener\" target=\"_blank\">Q-cells website<\/a><\/p>\n<p><a href=\"https:\/\/www.solaxpower.com\/\" rel=\"noopener\" target=\"_blank\">Solax website<\/a><\/p>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t\n<h2>Offerte<\/h2>\n<p><br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<\/p>\n<h2>Progetti<\/h2>\n<p><br \/>\n&nbsp;<br \/>\n<br \/>\n&nbsp;<br \/>\n<br \/>\n\r\n\t\t<div class=\"divider4\"><span><\/span><\/div>\r\n\t\t<br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f392-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"392\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/1842#wpcf7-f392-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"392\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f392-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> <\/label>\n<\/p>\n<h2>Contact\n<\/h2>\n<p>&nbsp;<br \/>\n<label> N\u2019h\u00e9sitez pas \u00e0 nous contacter pour toute question concernant nos offres ou nos produitss <\/label>\n<\/p>\n<p><label> \u00c9crivez \u00e0 <a href=\"mailto:info@seasolar.it\">info@seasolar.it<\/a> ou remplissez le formulaire suivant et nous vous contacterons: <\/label>\n<\/p>\n<p><label> Nom *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n<\/p>\n<p><label> Num\u00e9ro de t\u00e9l\u00e9phone *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-826\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-826\" \/><\/span><\/label>\n<\/p>\n<p><label> Votre E-mail *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label> Sujet *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Message *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label> * champs requis <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVOYER\" \/>\n<\/p>\n<p><label><\/label>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<br \/>\n<span style=\"color: #ffffff;\">Fotovoltaico offerta impianto 80kW<\/span><\/p>\n<!-- sktbuilder starter --><script type=\"text\/javascript\" src=\"https:\/\/seasolar.it\/wp-content\/plugins\/skt-builder\/sktbuilder\/sktbuilder-frontend-starter.js\"><\/script><script type=\"text\/javascript\" src=\"https:\/\/seasolar.it\/wp-content\/plugins\/skt-builder\/sktbuilder-wordpress-driver.js\"><\/script><script type=\"text\/javascript\"> var starter = new SktbuilderStarter({\"mode\": \"prod\", \"skip\":[\"jquery\",\"underscore\",\"backbone\"],\"sktbuilderUrl\": \"https:\/\/seasolar.it\/wp-content\/plugins\/skt-builder\/sktbuilder\/\", \"driver\": new SktbuilderWordpressDriver({\"ajaxUrl\": \"https:\/\/seasolar.it\/wp-admin\/admin-ajax.php\", \"iframeUrl\": \"https:\/\/seasolar.it\/fr\/fotovoltaico-offerta-impianto-80kw\/?sktbuilder=true\", \"pageId\": 1842,  \"nonce\": \"fd2531d93a\", \"pages\": [], \"page\": \"Fotovoltaico offerta impianto 80kW\" }) });<\/script><!-- end sktbuilder starter -->","protected":false},"excerpt":{"rendered":"<p>Offerta impianto fotovoltaico \u201cchiavi in mano\u201d 80KW (terminata) L\u2019impianto fotovoltaico ha una potenza nominale di 80,08 KWp e comprende: 182 Moduli fotovoltaici in silicio monocristallino Q-CELLS da 440W, garanzia sul prodotto 25 anni, garanzia sulla produzione 30 anni Inverter trifase SOLAX da 80kW, sistema di monitoraggio e WI-FI integrati, funzione autoconsumo, garanzia sul prodotto 5<br \/><a class=\"moretag\" href=\"https:\/\/seasolar.it\/fr\/fotovoltaico-offerta-impianto-80kw\/\">+ Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[58,25,131],"tags":[28,29,30,31,32,33,36,37,38,39,40,41,42,43,44,45,46,47,48,49,50,51,137,110,53,54,55,56],"class_list":["post-1842","post","type-post","status-publish","format-standard","hentry","category-offer-industrial-pv-system","category-offers","category-power-80kw","tag-costi-fotovoltaico","tag-costi-impianti-fotovoltaici","tag-costi-pannelli-solari","tag-costo-fotovoltaico","tag-costo-impianto-fotovoltaico","tag-costo-pannelli-solari","tag-offerte-fotovoltaico","tag-offerte-impianti-fotovoltaici","tag-offerte-impianto-fotovoltaico","tag-offerte-pannelli-solari","tag-preventivi-fotovoltaico","tag-preventivi-impianti-fotovoltaici","tag-preventivi-pannelli-solari","tag-preventivo-fotovoltaico","tag-preventivo-impianto-fotovoltaico","tag-preventivo-pannelli-solari","tag-prezzi-fotovoltaico","tag-prezzi-impianti-fotovoltaici","tag-prezzi-pannelli-solari","tag-prezzo-fotovoltaico","tag-prezzo-impianto-fotovoltaico","tag-prezzo-pannelli-solari","tag-q-cells","tag-solax","tag-vendita-fotovoltaico","tag-vendita-impianti-fotovoltaici","tag-vendita-impianto-fotovoltaico","tag-vendita-pannelli-solari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fotovoltaico offerta impianto 80kW - Seasolar ESCo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotovoltaico offerta impianto 80kW\" \/>\n<meta property=\"og:description\" content=\"Offerta impianto fotovoltaico \u201cchiavi in mano\u201d 80KW (terminata) L\u2019impianto fotovoltaico ha una potenza nominale di 80,08 KWp e comprende: 182 Moduli fotovoltaici in silicio monocristallino Q-CELLS da 440W, garanzia sul prodotto 25 anni, garanzia sulla produzione 30 anni Inverter trifase SOLAX da 80kW, sistema di monitoraggio e WI-FI integrati, funzione autoconsumo, garanzia sul prodotto 5+ Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/\" \/>\n<meta property=\"og:site_name\" content=\"Seasolar ESCo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seasolargroup\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-02T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/seasolar.it\/wp-content\/uploads\/2025\/08\/seasolar_logo_2024_R.png?fit=1079%2C517&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1079\" \/>\n\t<meta property=\"og:image:height\" content=\"517\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Seasolar ESCo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:site\" content=\"@seasolargroup\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Seasolar ESCo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/\"},\"author\":{\"name\":\"Seasolar ESCo\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/#\\\/schema\\\/person\\\/5daae3479ed942a6fccb17d326b6eb50\"},\"headline\":\"Fotovoltaico offerta impianto 80kW\",\"datePublished\":\"2024-11-02T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\",\"keywords\":[\"costi fotovoltaico\",\"costi impianti fotovoltaici\",\"costi pannelli solari\",\"costo fotovoltaico\",\"costo impianto fotovoltaico\",\"costo pannelli solari\",\"offerte fotovoltaico\",\"offerte impianti fotovoltaici\",\"offerte impianto fotovoltaico\",\"offerte pannelli solari\",\"preventivi fotovoltaico\",\"preventivi impianti fotovoltaici\",\"preventivi pannelli solari\",\"preventivo fotovoltaico\",\"preventivo impianto fotovoltaico\",\"preventivo pannelli solari\",\"prezzi fotovoltaico\",\"prezzi impianti fotovoltaici\",\"prezzi pannelli solari\",\"prezzo fotovoltaico\",\"prezzo impianto fotovoltaico\",\"prezzo pannelli solari\",\"Q-CELLS\",\"SOLAX\",\"vendita fotovoltaico\",\"vendita impianti fotovoltaici\",\"vendita impianto fotovoltaico\",\"vendita pannelli solari\"],\"articleSection\":[\"Offre syst\u00e8me photovolta\u00efque industriel\",\"Offres\",\"Power 80kW\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/\",\"url\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/\",\"name\":\"Fotovoltaico offerta impianto 80kW - Seasolar ESCo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\",\"datePublished\":\"2024-11-02T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/seasolargroup.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/fotovoltaico-offerta-impianto-80kw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seasolar.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotovoltaico offerta impianto 80kW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/#website\",\"url\":\"https:\\\/\\\/seasolar.it\\\/\",\"name\":\"Seasolar ESCo\",\"description\":\"Dal 2008 consulenza energetica per privati e imprese\",\"publisher\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seasolar.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/#organization\",\"name\":\"Seasolar ESCo\",\"url\":\"https:\\\/\\\/seasolar.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seasolar.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"contentUrl\":\"https:\\\/\\\/seasolar.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-seasolar_logo_2024_social.png\",\"width\":512,\"height\":512,\"caption\":\"Seasolar ESCo\"},\"image\":{\"@id\":\"https:\\\/\\\/seasolar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/seasolargroup\",\"https:\\\/\\\/x.com\\\/seasolargroup\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/seasolar-group-news\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVrmhrGih_bFnpj0as_vDuQ\",\"https:\\\/\\\/www.instagram.com\\\/fotovoltaico_seasolar\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seasolar.it\\\/#\\\/schema\\\/person\\\/5daae3479ed942a6fccb17d326b6eb50\",\"name\":\"Seasolar ESCo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g\",\"caption\":\"Seasolar ESCo\"},\"sameAs\":[\"https:\\\/\\\/seasolar.it\"],\"url\":\"https:\\\/\\\/seasolar.it\\\/fr\\\/author\\\/seasolar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fotovoltaico offerta impianto 80kW - Seasolar ESCo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/","og_locale":"fr_FR","og_type":"article","og_title":"Fotovoltaico offerta impianto 80kW","og_description":"Offerta impianto fotovoltaico \u201cchiavi in mano\u201d 80KW (terminata) L\u2019impianto fotovoltaico ha una potenza nominale di 80,08 KWp e comprende: 182 Moduli fotovoltaici in silicio monocristallino Q-CELLS da 440W, garanzia sul prodotto 25 anni, garanzia sulla produzione 30 anni Inverter trifase SOLAX da 80kW, sistema di monitoraggio e WI-FI integrati, funzione autoconsumo, garanzia sul prodotto 5+ Read More","og_url":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/","og_site_name":"Seasolar ESCo","article_publisher":"https:\/\/www.facebook.com\/seasolargroup","article_published_time":"2024-11-02T23:00:00+00:00","og_image":[{"width":1079,"height":517,"url":"https:\/\/i0.wp.com\/seasolar.it\/wp-content\/uploads\/2025\/08\/seasolar_logo_2024_R.png?fit=1079%2C517&ssl=1","type":"image\/png"}],"author":"Seasolar ESCo","twitter_card":"summary_large_image","twitter_creator":"@seasolargroup","twitter_site":"@seasolargroup","twitter_misc":{"\u00c9crit par":"Seasolar ESCo","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#article","isPartOf":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/"},"author":{"name":"Seasolar ESCo","@id":"https:\/\/seasolar.it\/#\/schema\/person\/5daae3479ed942a6fccb17d326b6eb50"},"headline":"Fotovoltaico offerta impianto 80kW","datePublished":"2024-11-02T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/seasolar.it\/#organization"},"image":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2020\/04\/logo.png","keywords":["costi fotovoltaico","costi impianti fotovoltaici","costi pannelli solari","costo fotovoltaico","costo impianto fotovoltaico","costo pannelli solari","offerte fotovoltaico","offerte impianti fotovoltaici","offerte impianto fotovoltaico","offerte pannelli solari","preventivi fotovoltaico","preventivi impianti fotovoltaici","preventivi pannelli solari","preventivo fotovoltaico","preventivo impianto fotovoltaico","preventivo pannelli solari","prezzi fotovoltaico","prezzi impianti fotovoltaici","prezzi pannelli solari","prezzo fotovoltaico","prezzo impianto fotovoltaico","prezzo pannelli solari","Q-CELLS","SOLAX","vendita fotovoltaico","vendita impianti fotovoltaici","vendita impianto fotovoltaico","vendita pannelli solari"],"articleSection":["Offre syst\u00e8me photovolta\u00efque industriel","Offres","Power 80kW"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/","url":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/","name":"Fotovoltaico offerta impianto 80kW - Seasolar ESCo","isPartOf":{"@id":"https:\/\/seasolar.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#primaryimage"},"image":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#primaryimage"},"thumbnailUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2020\/04\/logo.png","datePublished":"2024-11-02T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#primaryimage","url":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2020\/04\/logo.png","contentUrl":"https:\/\/seasolargroup.com\/wp-content\/uploads\/2020\/04\/logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/seasolar.it\/fotovoltaico-offerta-impianto-80kw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seasolar.it\/"},{"@type":"ListItem","position":2,"name":"Fotovoltaico offerta impianto 80kW"}]},{"@type":"WebSite","@id":"https:\/\/seasolar.it\/#website","url":"https:\/\/seasolar.it\/","name":"Seasolar ESCo","description":"Dal 2008 consulenza energetica per privati e imprese","publisher":{"@id":"https:\/\/seasolar.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seasolar.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/seasolar.it\/#organization","name":"Seasolar ESCo","url":"https:\/\/seasolar.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seasolar.it\/#\/schema\/logo\/image\/","url":"https:\/\/seasolar.it\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","contentUrl":"https:\/\/seasolar.it\/wp-content\/uploads\/2025\/08\/cropped-seasolar_logo_2024_social.png","width":512,"height":512,"caption":"Seasolar ESCo"},"image":{"@id":"https:\/\/seasolar.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/seasolargroup","https:\/\/x.com\/seasolargroup","https:\/\/www.linkedin.com\/in\/seasolar-group-news\/","https:\/\/www.youtube.com\/channel\/UCVrmhrGih_bFnpj0as_vDuQ","https:\/\/www.instagram.com\/fotovoltaico_seasolar\/"]},{"@type":"Person","@id":"https:\/\/seasolar.it\/#\/schema\/person\/5daae3479ed942a6fccb17d326b6eb50","name":"Seasolar ESCo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1895535ab2ecac4794ebf6445511476d56ab1ef8ee96b04bbbfb5191e3c553b5?s=96&d=mm&r=g","caption":"Seasolar ESCo"},"sameAs":["https:\/\/seasolar.it"],"url":"https:\/\/seasolar.it\/fr\/author\/seasolar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/posts\/1842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/comments?post=1842"}],"version-history":[{"count":0,"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/posts\/1842\/revisions"}],"wp:attachment":[{"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/media?parent=1842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/categories?post=1842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seasolar.it\/fr\/wp-json\/wp\/v2\/tags?post=1842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}